{"id":9609,"date":"2022-12-16T11:44:01","date_gmt":"2022-12-16T14:44:01","guid":{"rendered":"http:\/\/www.todoriego.com.ar\/site\/?post_type=product&#038;p=9609"},"modified":"2022-12-16T11:44:02","modified_gmt":"2022-12-16T14:44:02","slug":"tapon-hembra","status":"publish","type":"product","link":"https:\/\/www.todoriego.com.ar\/site\/producto\/tapon-hembra\/","title":{"rendered":"Tap\u00f3n Hembra"},"content":{"rendered":"<div class=\"wrapper2\">\n<div class=\"fright\">\n<div class=\"short_desc\">Los accesorios de presi\u00f3n de Hidroten son elementos de enlace para conducciones que han sido dise\u00f1adas para que uno o todos sus extremos sean unidos mediante sistemas de encolado.<\/div>\n<div class=\"product-box2\">\n<div class=\"clear\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"clear\"><\/div>\n<div class=\"example2\">\n<div class=\"tabs_show\">\n<div class=\"responsive-tabs-wrapper\">\n<div class=\"responsive-tabs responsive-tabs--enabled\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-8735\" src=\"https:\/\/www.todoriego.com.ar\/site\/wp-content\/uploads\/2022\/07\/hidroten.png\" alt=\"hidroten\" width=\"103\" height=\"50\" \/><\/p>\n","protected":false},"featured_media":9440,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[98,30,38],"product_tag":[],"class_list":{"0":"post-9609","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accesorios-de-pvc","7":"product_cat-agricultura","8":"product_cat-tuberias-de-conduccion-y-accesorios","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tap\u00f3n Hembra - Todoriego Insumos SRL<\/title>\n<meta name=\"description\" content=\"Los accesorios de presi\u00f3n de Hidroten son elementos de enlace para conducciones que han sido dise\u00f1adas para que uno o todos sus extremos sean unidos mediante sistemas de encolado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.todoriego.com.ar\/site\/producto\/tapon-hembra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tap\u00f3n Hembra - Todoriego Insumos SRL\" \/>\n<meta property=\"og:description\" content=\"Los accesorios de presi\u00f3n de Hidroten son elementos de enlace para conducciones que han sido dise\u00f1adas para que uno o todos sus extremos sean unidos mediante sistemas de encolado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.todoriego.com.ar\/site\/producto\/tapon-hembra\/\" \/>\n<meta property=\"og:site_name\" content=\"Todoriego Insumos SRL\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/todoriegoinsumos\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-16T14:44:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.todoriego.com.ar\/site\/wp-content\/uploads\/2022\/12\/productos_agricultura_tucon_24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/producto\\\/tapon-hembra\\\/\",\"url\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/producto\\\/tapon-hembra\\\/\",\"name\":\"Tap\u00f3n Hembra - Todoriego Insumos SRL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/producto\\\/tapon-hembra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/producto\\\/tapon-hembra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/productos_agricultura_tucon_24.jpg\",\"datePublished\":\"2022-12-16T14:44:01+00:00\",\"dateModified\":\"2022-12-16T14:44:02+00:00\",\"description\":\"Los accesorios de presi\u00f3n de Hidroten son elementos de enlace para conducciones que han sido dise\u00f1adas para que uno o todos sus extremos sean unidos mediante sistemas de encolado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/producto\\\/tapon-hembra\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/producto\\\/tapon-hembra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/producto\\\/tapon-hembra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/productos_agricultura_tucon_24.jpg\",\"contentUrl\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/productos_agricultura_tucon_24.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/producto\\\/tapon-hembra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tap\u00f3n Hembra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/\",\"name\":\"Todoriego Insumos SRL\",\"description\":\"Sabemos hacer riego\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/#organization\",\"name\":\"Todoriego Insumos s.r.l.\",\"url\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.todoriego.com.ar\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/todoriego_marca.jpg\",\"contentUrl\":\"http:\\\/\\\/www.todoriego.com.ar\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/todoriego_marca.jpg\",\"width\":731,\"height\":731,\"caption\":\"Todoriego Insumos s.r.l.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.todoriego.com.ar\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/todoriegoinsumos\\\/\",\"https:\\\/\\\/www.instagram.com\\\/todoriegoinsumos\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tap\u00f3n Hembra - Todoriego Insumos SRL","description":"Los accesorios de presi\u00f3n de Hidroten son elementos de enlace para conducciones que han sido dise\u00f1adas para que uno o todos sus extremos sean unidos mediante sistemas de encolado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.todoriego.com.ar\/site\/producto\/tapon-hembra\/","og_locale":"es_ES","og_type":"article","og_title":"Tap\u00f3n Hembra - Todoriego Insumos SRL","og_description":"Los accesorios de presi\u00f3n de Hidroten son elementos de enlace para conducciones que han sido dise\u00f1adas para que uno o todos sus extremos sean unidos mediante sistemas de encolado.","og_url":"https:\/\/www.todoriego.com.ar\/site\/producto\/tapon-hembra\/","og_site_name":"Todoriego Insumos SRL","article_publisher":"https:\/\/www.facebook.com\/todoriegoinsumos\/","article_modified_time":"2022-12-16T14:44:02+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.todoriego.com.ar\/site\/wp-content\/uploads\/2022\/12\/productos_agricultura_tucon_24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.todoriego.com.ar\/site\/producto\/tapon-hembra\/","url":"https:\/\/www.todoriego.com.ar\/site\/producto\/tapon-hembra\/","name":"Tap\u00f3n Hembra - Todoriego Insumos SRL","isPartOf":{"@id":"https:\/\/www.todoriego.com.ar\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.todoriego.com.ar\/site\/producto\/tapon-hembra\/#primaryimage"},"image":{"@id":"https:\/\/www.todoriego.com.ar\/site\/producto\/tapon-hembra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.todoriego.com.ar\/site\/wp-content\/uploads\/2022\/12\/productos_agricultura_tucon_24.jpg","datePublished":"2022-12-16T14:44:01+00:00","dateModified":"2022-12-16T14:44:02+00:00","description":"Los accesorios de presi\u00f3n de Hidroten son elementos de enlace para conducciones que han sido dise\u00f1adas para que uno o todos sus extremos sean unidos mediante sistemas de encolado.","breadcrumb":{"@id":"https:\/\/www.todoriego.com.ar\/site\/producto\/tapon-hembra\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.todoriego.com.ar\/site\/producto\/tapon-hembra\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/www.todoriego.com.ar\/site\/producto\/tapon-hembra\/#primaryimage","url":"https:\/\/www.todoriego.com.ar\/site\/wp-content\/uploads\/2022\/12\/productos_agricultura_tucon_24.jpg","contentUrl":"https:\/\/www.todoriego.com.ar\/site\/wp-content\/uploads\/2022\/12\/productos_agricultura_tucon_24.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.todoriego.com.ar\/site\/producto\/tapon-hembra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.todoriego.com.ar\/site\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.todoriego.com.ar\/site\/tienda\/"},{"@type":"ListItem","position":3,"name":"Tap\u00f3n Hembra"}]},{"@type":"WebSite","@id":"https:\/\/www.todoriego.com.ar\/site\/#website","url":"https:\/\/www.todoriego.com.ar\/site\/","name":"Todoriego Insumos SRL","description":"Sabemos hacer riego","publisher":{"@id":"https:\/\/www.todoriego.com.ar\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.todoriego.com.ar\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/www.todoriego.com.ar\/site\/#organization","name":"Todoriego Insumos s.r.l.","url":"https:\/\/www.todoriego.com.ar\/site\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/www.todoriego.com.ar\/site\/#\/schema\/logo\/image\/","url":"http:\/\/www.todoriego.com.ar\/site\/wp-content\/uploads\/2022\/07\/todoriego_marca.jpg","contentUrl":"http:\/\/www.todoriego.com.ar\/site\/wp-content\/uploads\/2022\/07\/todoriego_marca.jpg","width":731,"height":731,"caption":"Todoriego Insumos s.r.l."},"image":{"@id":"https:\/\/www.todoriego.com.ar\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/todoriegoinsumos\/","https:\/\/www.instagram.com\/todoriegoinsumos\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.todoriego.com.ar\/site\/wp-json\/wp\/v2\/product\/9609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoriego.com.ar\/site\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.todoriego.com.ar\/site\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoriego.com.ar\/site\/wp-json\/wp\/v2\/media\/9440"}],"wp:attachment":[{"href":"https:\/\/www.todoriego.com.ar\/site\/wp-json\/wp\/v2\/media?parent=9609"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.todoriego.com.ar\/site\/wp-json\/wp\/v2\/product_brand?post=9609"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.todoriego.com.ar\/site\/wp-json\/wp\/v2\/product_cat?post=9609"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.todoriego.com.ar\/site\/wp-json\/wp\/v2\/product_tag?post=9609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}